{"id":37391,"date":"2026-05-28T16:35:01","date_gmt":"2026-05-28T14:35:01","guid":{"rendered":"https:\/\/tierschutz.com\/?page_id=37391"},"modified":"2026-05-29T13:47:22","modified_gmt":"2026-05-29T11:47:22","slug":"les-animaux-et-la-chaleur-estivale","status":"publish","type":"page","link":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/","title":{"rendered":"Les animaux et la chaleur estivale"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-20 has-background-dim\" style=\"background-color:#728293\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2501\" height=\"1667\" src=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild.jpg\" class=\"wp-block-cover__image-background wp-post-image\" alt=\"\" data-object-fit=\"cover\" data-object-position=\"50% 39%\" style=\"object-position:50% 39%;\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild.jpg 2501w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2501px) 100vw, 2501px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-background-color has-text-color\" id=\"h-proteger-les-animaux-de-la-chaleur\"><strong><strong>Prot\u00e9ger les animaux de la chaleur<\/strong><\/strong><\/h2>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull anchor-bar has-lightgray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-209adecf wp-block-group-is-layout-flex\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#hunde\">Chiens<\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#katzen\"><strong>Chats<\/strong><\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#nager\"><strong>Rongeurs<\/strong><\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#voegel\"><strong>Oiseaux<\/strong><\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#reptilien\"><strong>Reptiles<\/strong><\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><strong><a href=\"#pferde\">Chevaux<\/a><\/strong><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#nutztiere\"><strong>Animaux de rente et de p\u00e2turage<\/strong><\/a><\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"#wildtiere\"><strong>Animaux sauvages<\/strong><\/a><\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-text-align-center\" id=\"h-proteger-les-animaux-domestiques-de-la-chaleur\"><strong><strong>Prot\u00e9ger les animaux domestiques de la chaleur<\/strong><\/strong><\/h1>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\">Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention, il est important de bien conna\u00eetre leurs besoins et de prendre \u00e0 temps les mesures n\u00e9cessaires pour qu\u2019ils puissent se rafra\u00eechir. C\u2019est le seul moyen d\u2019\u00e9viter efficacement la surchauffe et les risques pour la sant\u00e9.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Chaque esp\u00e8ce animale a son propre confort thermique et r\u00e9agit diff\u00e9remment \u00e0 une forte chaleur. Il ne suffit donc pas de jeter un coup d\u2019\u0153il au thermom\u00e8tre pour d\u00e9cider si un animal a trop chaud. La temp\u00e9rature r\u00e9elle \u00e0 l\u2019endroit o\u00f9 se trouve l\u2019animal est d\u00e9terminante. Pour les petits animaux en particulier, la temp\u00e9rature peut \u00eatre nettement plus \u00e9lev\u00e9e dans l\u2019enclos ou la cage que dans le reste du logement. En effet, l\u2019exigu\u00eft\u00e9 de l\u2019espace, le rayonnement solaire direct ou une mauvaise circulation d\u2019air peuvent faire grimper rapidement la chaleur et l\u2019humidit\u00e9 de l\u2019air.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Moodbild-Hitze-1024x576.jpg\" alt=\"Comment prot\u00e9ger mon animal domestique de la chaleur ?\" class=\"wp-image-37351 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-1024x576.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-300x169.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-768x432.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-1536x864.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-2048x1152.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-500x281.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-800x450.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-1280x720.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Moodbild-Hitze-1920x1080.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-voici-ce-a-quoi-vous-devez-faire-attention\"><strong>Voici ce \u00e0 quoi vous devez faire attention :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-check\">En cas de chaleur, les animaux ont toujours besoin d\u2019ombre, d\u2019endroits frais o\u00f9 se r\u00e9fugier et d\u2019eau fra\u00eeche. Gardez \u00e0 l\u2019esprit que le soleil se d\u00e9place au cours de la journ\u00e9e\u00a0!<\/li>\n\n\n\n<li class=\"is-style-check\">Mesurez la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de la cage, de l\u2019enclos ou du terrarium, car elle y augmente plus rapidement.<\/li>\n\n\n\n<li class=\"is-style-check\">Les cages, enclos et terrariums ne doivent jamais \u00eatre expos\u00e9s aux rayons directs du soleil et\/ou recouverts de b\u00e2ches\/toiles, car cela provoque une accumulation de chaleur.<\/li>\n\n\n\n<li class=\"is-style-check\">Adaptez la routine quotidienne (p.\u00a0ex. en d\u00e9calant les promenades, l\u2019entra\u00eenement et les sorties aux heures plus fra\u00eeches du matin et du soir).<\/li>\n\n\n\n<li class=\"is-style-cross\">Ne forcez jamais votre animal \u00e0 prendre un bain froid \u2013 cela peut provoquer des probl\u00e8mes circulatoires.<\/li>\n\n\n\n<li class=\"is-style-cross\"><strong>Ne laissez jamais des animaux \u00e0 l\u2019int\u00e9rieur d\u2019une voiture en stationnement<\/strong> \u2013 il existe un danger de mort imm\u00e9diat d\u00fb \u00e0 la chaleur\u00a0: m\u00eame lorsque la temp\u00e9rature ext\u00e9rieure est d\u2019environ 15\u00a0\u00b0C, que le ciel est nuageux ou que les fen\u00eatres sont ouvertes, la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de l\u2019habitacle peut monter rapidement \u00e0 45\u00a0\u00b0C et plus en quelques minutes\u00a0!<\/li>\n\n\n\n<li class=\"is-style-cross\">Ne transportez pas d\u2019animaux par forte chaleur \u2013 une cage de transport, une caisse de transport ou un v\u00e9hicule sans climatisation risque rapidement de surchauffer.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-proteger-mon-animal-domestique-de-la-chaleur\"><strong><strong>Comment prot\u00e9ger mon animal domestique de la chaleur ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">D\u2019une mani\u00e8re g\u00e9n\u00e9rale, prot\u00e9gez votre animal domestique en lui offrant suffisamment d\u2019ombre, des endroits frais o\u00f9 se r\u00e9fugier, de l\u2019eau fra\u00eeche et une routine adapt\u00e9e. Les d\u00e9tentrices et d\u00e9tenteurs doivent toutefois imp\u00e9rativement conna\u00eetre la zone de confort thermique sp\u00e9cifique \u00e0 leur animal de compagnie, ainsi que la limite de temp\u00e9rature \u00e0 partir de laquelle le stress thermique s\u2019installe ou qu\u2019il y a un danger de mort. Ce n\u2019est qu\u2019en connaissant ces valeurs que l\u2019on peut prendre \u00e0 temps des mesures de protection et \u00e9viter des dommages pour la sant\u00e9.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-quels-animaux-domestiques-souffrent-particulierement-de-la-chaleur\"><strong><strong>Quels animaux domestiques souffrent particuli\u00e8rement de la chaleur ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les animaux domestiques qui r\u00e9gulent difficilement leur temp\u00e9rature corporelle sont particuli\u00e8rement sensibles \u00e0 la chaleur. Il s\u2019agit p. ex. des chiens \u00e0 museau plat, des animaux \u00e0 pelage \u00e9pais ou long, des animaux \u00e2g\u00e9s ou souffrant de maladies chroniques ainsi que des animaux tr\u00e8s jeunes. Les animaux se trouvant dans des enclos, des cages, des terrariums, des cages de transport mal ventil\u00e9es ou dans des voitures sont \u00e9galement expos\u00e9s \u00e0 un risque \u00e9lev\u00e9, car la temp\u00e9rature peut y monter rapidement et mettre leur vie en danger.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-les-animaux-domestiques-peuvent-ils-sortir-par-forte-chaleur\"><strong><strong>Les animaux domestiques peuvent-ils sortir par forte chaleur ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Uniquement si l\u2019enclos est bien pr\u00e9par\u00e9 et si toutes les mesures de protection ont \u00e9t\u00e9 prises. Il est important que vous connaissiez la zone de confort thermique de votre animal et que vous sachiez \u00e0 partir de quand la chaleur devient dangereuse pour lui. Si, malgr\u00e9 les mesures de protection, la temp\u00e9rature dans l\u2019enclos devient trop \u00e9lev\u00e9e, d\u00e9placez l\u2019animal dans un endroit plus frais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-important\"><strong>Important :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Lors de journ\u00e9es tr\u00e8s chaudes, il ne suffit pas de pr\u00e9voir de l\u2019ombre, car m\u00eame \u00e0 l\u2019ombre, il peut faire tr\u00e8s chaud. C\u2019est pourquoi, outre des zones ombrag\u00e9es suffisamment grandes, il faut aussi toujours veiller \u00e0 tenir de l\u2019eau fra\u00eeche \u00e0 disposition et \u00e0 proposer des zones nettement plus fra\u00eeches, p.\u00a0ex. sous les arbres, dans des endroits bien ventil\u00e9s et sur l\u2019herbe plut\u00f4t que sur la pierre ou l\u2019asphalte (car ceux-ci peuvent devenir tr\u00e8s chauds).<\/li>\n\n\n\n<li class=\"is-style-default\">Les rongeurs, lapins, reptiles et oiseaux plac\u00e9s sur le balcon ou dans le jardin ne doivent jamais \u00eatre expos\u00e9s directement au soleil. Tenez donc toujours compte de la course du soleil pour \u00e9viter les rayons directs du soleil et n\u2019oubliez pas que la temp\u00e9rature et l\u2019humidit\u00e9 de l\u2019air augmentent plus rapidement \u00e0 l\u2019int\u00e9rieur de l\u2019enclos qu\u2019\u00e0 l\u2019ext\u00e9rieur. <\/li>\n\n\n\n<li class=\"is-style-default\">Il n\u2019est pas forc\u00e9ment plus s\u00fbr d\u2019amener simplement les animaux \u00e0 l\u2019int\u00e9rieur, car la temp\u00e9rature peut aussi y augmenter consid\u00e9rablement (surtout dans les pi\u00e8ces non climatis\u00e9es). Il est essentiel que l\u2019animal se trouve \u00e0 tout moment dans sa zone de confort thermique et qu\u2019il ait toujours de l\u2019eau fra\u00eeche et des possibilit\u00e9s de se rafra\u00eechir.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-comment-proteger-votre-animal-domestique-de-la-chaleur\"><strong>Comment prot\u00e9ger votre animal domestique de la chaleur<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<div class=\"wp-block-group is-layout-flex wp-container-core-group-is-layout-0eba7147 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-style-shadow-box has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-a-l-interieur-prevoir-des-endroits-frais\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\"><strong>\u00c0 l\u2019int\u00e9rieur : <\/strong><br><\/mark><strong>pr\u00e9voir des endroits frais<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-check\">Maintenez le logement aussi frais que possible (p. ex., fermez les fen\u00eatres et les volets pendant la journ\u00e9e, a\u00e9rez la nuit).<\/li>\n\n\n\n<li class=\"is-style-check\">Proposez \u00e0 vos animaux des endroits frais adapt\u00e9s, comme des sols en carrelage, des tapis rafra\u00eechissants sp\u00e9ciaux, des espaces de baignade ou des linges humides.<\/li>\n\n\n\n<li class=\"is-style-check\">De l\u2019eau fra\u00eeche doit toujours \u00eatre disponible \u2013 pour les chats, il est recommand\u00e9 de proposer de l\u2019eau \u00e0 plusieurs endroits et dans diff\u00e9rents r\u00e9cipients.<\/li>\n\n\n\n<li class=\"is-style-check\">Assurez-vous que l\u2019air peut bien circuler dans l\u2019enclos, la cage ou le terrarium.<\/li>\n\n\n\n<li class=\"is-style-check\">Les cages et terrariums ne doivent jamais \u00eatre expos\u00e9s directement au soleil, car ils se r\u00e9chauffent rapidement (tenir compte de la course du soleil !)<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-shadow-box has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-a-l-exterieur-creer-des-possibilites-de-rafraichissement\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">\u00c0 l\u2019ext\u00e9rieur<\/mark><\/strong> <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-secondary-color\">:<\/mark><\/strong><br><strong>cr\u00e9er des possibilit\u00e9s de rafra\u00eechissement<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-check\">Les chiens et les chats doivent toujours avoir acc\u00e8s \u00e0 des endroits ombrag\u00e9s \u00e0 l\u2019ext\u00e9rieur, id\u00e9alement sous les arbres ou les arbustes.<\/li>\n\n\n\n<li class=\"is-style-check\">Les oiseaux, reptiles, rongeurs et lapins plac\u00e9s sur le balcon ou dans le jardin ne doivent jamais \u00eatre expos\u00e9s directement au soleil. Eux aussi doivent pouvoir acc\u00e9der \u00e0 tout moment \u00e0 des zones ombrag\u00e9es suffisamment grandes dans leur enclos. V\u00e9rifiez la course du soleil et assurez-vous que les animaux ont de l\u2019ombre toute la journ\u00e9e.<\/li>\n\n\n\n<li class=\"is-style-check\">Veillez \u00e0 ce que l\u2019air puisse bien circuler dans l\u2019enclos.<\/li>\n\n\n\n<li class=\"is-style-check\">S\u2019il fait trop chaud m\u00eame \u00e0 l\u2019ombre, d\u00e9placez les animaux dans un endroit plus frais.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-mon-animal-domestique-est-en-surchauffe-et-a-besoin-d-une-aide-medicale\"><strong><strong>Comment savoir si mon animal domestique est en surchauffe et a besoin d\u2019une aide m\u00e9dicale ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les sympt\u00f4mes suivants chez votre animal domestique peuvent indiquer une surchauffe ou un coup de chaleur. Mettez imm\u00e9diatement votre animal dans un endroit frais et appelez sans attendre le v\u00e9t\u00e9rinaire, car une surchauffe est une urgence pouvant mettre sa vie en danger.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chats :<\/strong> hal\u00e8tement, agitation, apathie, vomissements<br>\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/li>\n\n\n\n<li><strong>Chiens :<\/strong> hal\u00e8tement intense, agitation, salivation accrue, langue fortement pendante<br>\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/li>\n\n\n\n<li><strong>Rongeurs :<\/strong> respiration rapide, position allong\u00e9e, apathie<br>\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/li>\n\n\n\n<li><strong>Oiseaux :<\/strong> respiration rapide, ailes \u00e9cart\u00e9es, apathie ou agitation, vacillement<br>\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/li>\n\n\n\n<li><strong>Reptiles :<\/strong> perte d\u2019app\u00e9tit, agitation ou apathie, respiration acc\u00e9l\u00e9r\u00e9e (hal\u00e8tement), faiblesse, troubles de l\u2019\u00e9quilibre et de la motricit\u00e9, formation de mousse au niveau de la gueule, vomissements ou perte de connaissance.<br>\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conseil :<\/strong> renseignez-vous sur les cours de premiers secours pour animaux, p. ex. dans les \u00e9coles canines ou les cabinets v\u00e9t\u00e9rinaires. Vous apprendrez ainsi \u00e0 reconna\u00eetre une situation d\u2019urgence et \u00e0 r\u00e9agir correctement.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-un-ventilateur-est-il-dangereux-pour-les-animaux-domestiques\"><strong><strong><strong>Un ventilateur est-il dangereux pour les animaux domestiques ?<\/strong><\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Oui.<\/strong> Le flux d\u2019air direct peut irriter les yeux et les voies respiratoires de votre animal domestique. Les ventilateurs ne doivent donc jamais \u00eatre orient\u00e9s directement vers les animaux, mais ils peuvent \u00eatre utilis\u00e9s pour rafra\u00eechir l\u2019air ambiant.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-que-faire-si-mon-chien-ou-mon-chat-est-en-surchauffe\"><strong><strong><strong>Que faire si mon chien ou mon chat est en surchauffe ?<\/strong><\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Mettez imm\u00e9diatement l\u2019animal \u00e0 l\u2019ombre ou dans une pi\u00e8ce fra\u00eeche, proposez de l\u2019eau, refroidissez le corps avec des linges humides et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"hunde\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-chiens\"><strong><strong>Rafra\u00eechir les chiens<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les chiens ne transpirent que par leurs pattes et leur truffe, ce qui ne suffit pas \u00e0 r\u00e9guler leur temp\u00e9rature. Ils ne peuvent se refroidir qu\u2019en haletant. Il est donc important de les prot\u00e9ger des fortes chaleurs et de leur offrir en permanence des possibilit\u00e9s de se rafra\u00eechir. Les chiens au museau plat (p. ex. carlins, bouledogues fran\u00e7ais) et ceux au pelage long et \u00e9pais (p. ex. loulou de Pom\u00e9ranie) sont particuli\u00e8rement sensibles \u00e0 la chaleur. Une attention particuli\u00e8re doit \u00eatre port\u00e9e \u00e0 l\u2019identification des signaux d\u2019alerte.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-1024x683.jpg\" alt=\"Prot\u00e9ger les chiens de la chaleur\" class=\"wp-image-37347 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hund-auf-Asphalt-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-chiens-de-la-chaleur\"><strong>Prot\u00e9ger les chiens de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Promenez les chiens uniquement pendant les heures fra\u00eeches du matin et du soir. Si votre chien aime se baigner, les points d\u2019eau sont id\u00e9aux pour se rafra\u00eechir. <br><strong>Attention :<\/strong> les algues bleues sont tr\u00e8s toxiques pour les chiens. V\u00e9rifiez donc au pr\u00e9alable la qualit\u00e9 de l\u2019eau et les avis d\u2019alerte r\u00e9gionaux.<\/li>\n\n\n\n<li>L\u2019asphalte chaud peut br\u00fbler ses pattes \u2013 v\u00e9rifiez avec la main si le sol est trop chaud.<\/li>\n\n\n\n<li>Veillez \u00e0 toujours avoir de l\u2019eau fra\u00eeche \u00e0 disposition.<\/li>\n\n\n\n<li>Changez l\u2019eau plusieurs fois par jour.<\/li>\n\n\n\n<li>Beaucoup de chiens aiment prendre un bain. Proposez-leur, mais ne les forcez pas.<\/li>\n\n\n\n<li>Ne laissez jamais un chien dans une voiture, car la temp\u00e9rature (d\u00e8s 15 \u00b0C \u00e0 l\u2019ext\u00e9rieur !) peut monter en quelques minutes, mettant sa vie en danger.<\/li>\n\n\n\n<li class=\"is-style-default\">D\u00e9calez l\u2019entra\u00eenement aux heures fra\u00eeches du matin ou du soir et adaptez l\u2019intensit\u00e9 et la dur\u00e9e aux temp\u00e9ratures (m\u00eame lors d\u2019activit\u00e9s olfactives comme le mantrailing, la d\u00e9tection d\u2019odeurs ou la recherche de pistes, la temp\u00e9rature corporelle peut consid\u00e9rablement augmenter).<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/tierschutz.com\/fr\/detention-des-animaux\/detention-danimaux-de-compagnie\/detention-de-chiens\/\"><strong>En savoir plus sur la d\u00e9tention des chiens<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-file-wrapper is-pdf\" data-filetype=\"PDF\" data-size=\"349 Ko\">\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-70474ab6-f1b9-46b8-9fd9-07459c6671d9\" href=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/flyer_sommerhitze_fr.pdf\">Risque de surchauffe dans la voiture<\/a><a href=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/flyer_sommerhitze_fr.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-70474ab6-f1b9-46b8-9fd9-07459c6671d9\">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"katzen\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-chats\"><strong><strong><strong>Rafra\u00eechir les chats<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les chats supportent g\u00e9n\u00e9ralement bien la chaleur s\u00e8che, mais lorsqu\u2019il fait tr\u00e8s chaud, lorsqu\u2019il n\u2019y a pas de possibilit\u00e9s de s\u2019isoler et surtout dans les appartements, ils ont eux aussi besoin d\u2019aide pour se rafra\u00eechir. Comme les chats boivent souvent peu, il est important de les inciter \u00e0 boire en multipliant les points d\u2019eau.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-chats-de-la-chaleur\"><strong>Prot\u00e9ger les chats de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Mettez de l\u2019eau fra\u00eeche \u00e0 disposition et changez-la plusieurs fois par jour.<\/li>\n\n\n\n<li>Placez plusieurs r\u00e9cipients d\u2019eau\/fontaines \u00e0 des endroits diff\u00e9rents.<\/li>\n\n\n\n<li>Donnez de la nourriture humide plut\u00f4t que s\u00e8che (les chats couvrent la majeure partie de leurs besoins hydriques par le biais de la nourriture).<\/li>\n\n\n\n<li>Proposez des tapis rafra\u00eechissants ou du carrelage frais comme point de repli.<\/li>\n\n\n\n<li>Les chats qui sortent librement doivent pouvoir choisir eux-m\u00eames s\u2019ils veulent \u00eatre \u00e0 l\u2019ext\u00e9rieur ou \u00e0 l\u2019int\u00e9rieur.<\/li>\n\n\n\n<li class=\"is-style-default\">En raison de l\u2019absence de pelage, les chats nus (Sphynx) doivent \u00eatre particuli\u00e8rement prot\u00e9g\u00e9s contre les coups de soleil. \u00c9vitez les rayons directs du soleil ou appliquez une cr\u00e8me solaire adapt\u00e9e aux chats.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/tierschutz.com\/fr\/detention-des-animaux\/detention-danimaux-de-compagnie\/detention-de-chats\/\">En savoir plus sur la d\u00e9tention des chats<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Katze-am-trinken-1024x683.jpg\" alt=\"Prot\u00e9ger les chats de la chaleur\" class=\"wp-image-37349 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Katze-am-trinken-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"nager\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-petits-animaux-et-les-rongeurs\"><strong><strong><strong><strong>Rafra\u00eechir les petits animaux et les rongeurs<\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Dans la nature, de nombreux petits animaux et rongeurs r\u00e9gulent leur temp\u00e9rature corporelle principalement en recherchant des endroits frais (p. ex. syst\u00e8mes de galeries souterraines). D\u00e8s 25 \u00b0C, la chaleur peut d\u00e9j\u00e0 \u00eatre mortelle pour les petits rongeurs, car leur zone de confort thermique se situe entre 18 et 20 \u00b0C. Il est donc important de surveiller la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de l\u2019enclos et de veiller \u00e0 ce qu\u2019il y ait suffisamment d\u2019ombre, d\u2019air frais et de possibilit\u00e9s de rafra\u00eechissement.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Meerschweinchen-1024x681.jpg\" alt=\"Prot\u00e9ger les cochons d\u2019Inde et les lapins de la chaleur\" class=\"wp-image-37350 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-1024x681.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-768x511.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-1536x1022.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-2048x1363.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-800x532.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-1280x852.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Meerschweinchen-1920x1278.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-cochons-d-inde-et-les-lapins-de-la-chaleur\"><strong>Prot\u00e9ger les cochons d\u2019Inde et les lapins de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Mesurez r\u00e9guli\u00e8rement la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de l\u2019enclos, car la temp\u00e9rature et l\u2019humidit\u00e9 de l\u2019air y sont souvent plus \u00e9lev\u00e9es qu\u2019\u00e0 l\u2019ext\u00e9rieur.<\/li>\n\n\n\n<li>Mettez toujours de l\u2019eau fra\u00eeche \u00e0 disposition \u2013 changez l\u2019eau une \u00e0 deux fois par jour.<\/li>\n\n\n\n<li>Donnez des l\u00e9gumes riches en eau (comme des concombres).<\/li>\n\n\n\n<li>Ne placez jamais les enclos au soleil, m\u00eame partiellement. V\u00e9rifiez l\u2019ensoleillement tout au long de la journ\u00e9e, car l\u2019ombre se d\u00e9place ! <br><strong>Attention :<\/strong> les b\u00e2ches pos\u00e9es au-dessus de l\u2019enclos provoquent une accumulation de chaleur et sont dangereuses.<\/li>\n\n\n\n<li>Pr\u00e9voyez suffisamment d\u2019ombre et des endroits frais dans le jardin. S\u2019il fait trop chaud, d\u00e9placez les animaux dans un endroit plus frais.<\/li>\n\n\n\n<li>Sur le balcon, il est indispensable de v\u00e9rifier et mesurer avec pr\u00e9cision la temp\u00e9rature atteinte pendant la journ\u00e9e. S\u2019il fait trop chaud, m\u00eame sans exposition directe au soleil, les animaux ne doivent pas rester sur le balcon.<\/li>\n\n\n\n<li>Cr\u00e9ez des endroits frais dans l\u2019enclos : placez des carreaux, des dalles en pierre, des pots en terre cuite humides et des branches avec des feuilles non toxiques (!).<\/li>\n\n\n\n<li class=\"is-style-default\">Des parasols et un drap blanc (sec ou mouill\u00e9) peuvent \u00e9galement \u00eatre utilis\u00e9s pour couvrir l\u2019enclos. Important : ne couvrez jamais tout l\u2019enclos, car l\u2019air doit pouvoir circuler librement de tous les c\u00f4t\u00e9s).<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-hamsters-de-la-chaleur\"><strong>Prot\u00e9ger les hamsters de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Les hamsters ont imp\u00e9rativement besoin d\u2019un endroit frais et ombrag\u00e9. La cage ne doit jamais \u00eatre expos\u00e9e au soleil, m\u00eame partiellement. V\u00e9rifiez l\u2019ensoleillement tout au long de la journ\u00e9e, car l\u2019ombre se d\u00e9place !<\/li>\n\n\n\n<li>Contr\u00f4lez r\u00e9guli\u00e8rement la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de la cage \u2013 s\u2019il y fait trop chaud, placez-la dans un endroit plus frais.<\/li>\n\n\n\n<li>Outre le soleil direct, veillez aussi \u00e0 \u00e9viter les courants d\u2019air.<\/li>\n\n\n\n<li>Pour rafra\u00eechir votre animal, placez des carreaux humides, des dalles de pierre ou des pots en terre cuite dans l\u2019enclos.<\/li>\n\n\n\n<li class=\"is-style-default\">Pr\u00e9voyez toujours de l\u2019eau fra\u00eeche \u2013 les hamsters boivent plus que d\u2019habitude lorsqu\u2019il fait chaud. Changez l\u2019eau une \u00e0 deux fois par jour.<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"660\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Hamster-1024x660.jpg\" alt=\"Prot\u00e9ger les hamsters de la chaleur\" class=\"wp-image-37344 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-1024x660.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-300x193.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-768x495.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-1536x990.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-2048x1320.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-500x322.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-800x516.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-1280x825.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Hamster-1920x1237.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a33614f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/tierschutz.com\/fr\/detention-des-animaux\/detention-danimaux-de-compagnie\/elevage-de-rongeurs-lapins\/\">En savoir plus sur la d\u00e9tention de petits animaux<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"voegel\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-oiseaux\"><strong><strong>Rafra\u00eechir les oiseaux<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Bien que les oiseaux aient une temp\u00e9rature corporelle d\u2019environ 40 \u00b0C et supportent mieux la chaleur que les humains, ils courent tout de m\u00eame un risque de surchauffe \u00e0 partir de 30 \u00b0C. En effet, les oiseaux ne transpirent pas \u2013 ils se refroidissent en haletant, en se reposant, en cherchant des zones ombrag\u00e9es fra\u00eeches et en se baignant.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Nymphensittich-1024x683.jpg\" alt=\"Prot\u00e9ger les oiseaux de la chaleur\" class=\"wp-image-37352 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Nymphensittich-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-oiseaux-de-la-chaleur\"><strong>Prot\u00e9ger les oiseaux de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Mettez toujours de l\u2019eau fra\u00eeche \u00e0 disposition.<\/li>\n\n\n\n<li>Gardez toujours les cages \u00e0 oiseaux \u00e0 l\u2019ombre.<\/li>\n\n\n\n<li>Les voli\u00e8res doivent toujours disposer d\u2019espaces ensoleill\u00e9s et ombrag\u00e9s afin que les oiseaux puissent s\u2019installer o\u00f9 ils veulent.<\/li>\n\n\n\n<li>V\u00e9rifiez l\u2019ensoleillement tout au long de la journ\u00e9e, car l\u2019ombre se d\u00e9place ! <br><strong>Attention :<\/strong> les b\u00e2ches pos\u00e9es au-dessus de l\u2019enclos provoquent une accumulation de chaleur et sont dangereuses.<\/li>\n\n\n\n<li>\u00c9vitez les courants d\u2019air.<\/li>\n\n\n\n<li>Pr\u00e9voyez toujours des possibilit\u00e9s de baignade (bassins, etc.) et changez l\u2019eau au moins une fois par jour.<\/li>\n\n\n\n<li class=\"is-style-default\">Les branches avec des feuilles fra\u00eeches non toxiques (!) offrent de l\u2019ombre et une occupation.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/tierschutz.com\/fr\/detention-des-animaux\/detention-danimaux-de-compagnie\/detention-doiseaux\/\"><strong>En savoir plus sur la d\u00e9tention d\u2019oiseaux<\/strong><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"reptilien\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-reptiles\"><strong><strong>Rafra\u00eechir les reptiles<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les reptiles sont des animaux \u00e0 sang froid. Le matin surtout, les serpents, les l\u00e9zards, les grenouilles et les tortues ont besoin de chaleur ext\u00e9rieure pour se mettre en mouvement. \u00c0 midi, lorsque la chaleur est intense, il fait alors trop chaud pour eux aussi et ils se retirent g\u00e9n\u00e9ralement \u00e0 l\u2019ombre. Toutefois, cela n\u2019est souvent pas possible dans un terrarium chauff\u00e9 ou mal ventil\u00e9. C\u2019est pourquoi une vigilance particuli\u00e8re s\u2019impose : le terrarium peut se r\u00e9chauffer en peu de temps et mettre leur vie en danger.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-reptiles-de-la-chaleur\"><strong>Prot\u00e9ger les reptiles de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Mettez toujours suffisamment d\u2019eau \u00e0 disposition.<\/li>\n\n\n\n<li>\u00c9vitez toute exposition directe aux rayons du soleil.<\/li>\n\n\n\n<li>Contr\u00f4lez r\u00e9guli\u00e8rement la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur du terrarium \u2013 le risque de surchauffe est \u00e9lev\u00e9, surtout l\u2019apr\u00e8s-midi, et peut mettre leur vie en danger.<\/li>\n\n\n\n<li>En cas de forte chaleur, r\u00e9duisez temporairement les syst\u00e8mes de chauffage et d\u2019\u00e9clairage ou \u00e9teignez-les compl\u00e8tement.<\/li>\n\n\n\n<li>Veillez \u00e0 ce que le terrarium soit bien a\u00e9r\u00e9 et qu\u2019il y ait une circulation d\u2019air suffisante (les ouvertures d\u2019a\u00e9ration ne doivent pas \u00eatre obstru\u00e9es par l\u2019\u00e9clairage ou des \u00e9l\u00e9ments d\u2019am\u00e9nagement).<\/li>\n\n\n\n<li>Pr\u00e9voyez des possibilit\u00e9s de rafra\u00eechissement dans le terrarium (d\u00e9posez des dalles de pierre fra\u00eeches ou des linges humides dans l\u2019enclos).<\/li>\n\n\n\n<li class=\"is-style-default\">Dans les enclos ext\u00e9rieurs, pr\u00e9voyez toujours des zones ombrag\u00e9es et des cachettes fra\u00eeches (v\u00e9rifiez la position du soleil toute la journ\u00e9e, car l\u2019ombre se d\u00e9place). <br><strong>Attention :<\/strong> les b\u00e2ches pos\u00e9es sur l\u2019enclos entra\u00eenent une accumulation de chaleur et sont dangereuses !<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-1024x683.jpg\" alt=\"Prot\u00e9ger les reptiles de la chaleur\" class=\"wp-image-5694 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-768x513.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-1536x1025.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2023\/06\/sts-reptilienhaltung-schlange-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Schildkroete-1024x683.jpg\" alt=\"Prot\u00e9ger les tortues terrestres de la chaleur\" class=\"wp-image-37354 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schildkroete-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-tortues-terrestres-de-la-chaleur\"><strong>Prot\u00e9ger les tortues terrestres de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Mettez toujours de l\u2019eau fra\u00eeche \u00e0 disposition<\/li>\n\n\n\n<li>Pour les enclos de tortues situ\u00e9s dans le jardin, pr\u00e9voyez toujours des arbustes bas sous lesquels les tortues peuvent se r\u00e9fugier pendant les heures les plus chaudes.<\/li>\n\n\n\n<li>Les tortues ont besoin de deux choses : des endroits chauds (surtout avec le soleil du matin) et des zones ombrag\u00e9es pour les apr\u00e8s-midi les plus chauds.<\/li>\n\n\n\n<li class=\"is-style-default\">Compl\u00e9tez leur alimentation avec des l\u00e9gumes riches en eau (p. ex. des concombres).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-mon-serpent-mon-lezard-ou-ma-tortue-est-en-surchauffe\"><strong><strong>Comment savoir si mon serpent, mon l\u00e9zard ou ma tortue est en surchauffe ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les sympt\u00f4mes courants de surchauffe et de coup de chaleur chez les reptiles sont une perte d\u2019app\u00e9tit, une agitation ou une apathie, une respiration acc\u00e9l\u00e9r\u00e9e (hal\u00e8tement), une faiblesse, des troubles de l\u2019\u00e9quilibre et de la motricit\u00e9, la formation de mousse au niveau de la gueule, des vomissements ou une perte de connaissance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez-lui de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-a-partir-de-quand-la-temperature-devient-elle-trop-elevee-pour-les-reptiles-et-met-elle-leur-vie-en-danger\"><strong><strong><strong>\u00c0 partir de quand la temp\u00e9rature devient-elle trop \u00e9lev\u00e9e pour les reptiles et met-elle leur vie en danger ?<\/strong><\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La zone de confort thermique des reptiles varie d\u2019une esp\u00e8ce \u00e0 l\u2019autre. Les esp\u00e8ces vivant dans le d\u00e9sert peuvent par exemple s\u2019adapter \u00e0 des temp\u00e9ratures plus \u00e9lev\u00e9es et se comporter normalement m\u00eame \u00e0 35\u00a0\u00b0C. D\u2019autres esp\u00e8ces ont besoin de temp\u00e9ratures nettement plus basses \u2013 renseignez-vous sur ce qui s\u2019applique \u00e0 votre animal et contr\u00f4lez r\u00e9guli\u00e8rement la temp\u00e9rature dans le terrarium.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Important<\/strong>\u00a0: comme les reptiles sont des animaux \u00e0 sang froid, ils ont besoin de zones plus fra\u00eeches dans leur enclos. M\u00eame les esp\u00e8ces qui aiment la chaleur doivent avoir la possibilit\u00e9 de s\u2019isoler \u00e0 tout moment dans des endroits frais, comme des zones ombrag\u00e9es, des cavit\u00e9s ou des endroits plus humides. En l\u2019absence de telles solutions de repli, le risque de surchauffe augmente rapidement. \u00c0 partir de 40\u00a0\u00b0C, le danger devient mortel, m\u00eame pour les esp\u00e8ces thermophiles.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"pferde\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-chevaux-les-anes-et-les-mulets\"><strong><strong>Rafra\u00eechir les chevaux, les \u00e2nes et les mulets<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les chevaux, les \u00e2nes et les mulets se rafra\u00eechissent principalement par la transpiration. Mais une chaleur intense et une forte humidit\u00e9 repr\u00e9sentent aussi un risque de surchauffe pour eux. Ils doivent donc toujours avoir acc\u00e8s \u00e0 une zone ombrag\u00e9e ou \u00e0 un abri bien ventil\u00e9 pour se prot\u00e9ger du soleil et des orages.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-chevaux-les-anes-et-les-mulets-de-la-chaleur\"><strong>Prot\u00e9ger les chevaux, les \u00e2nes et les mulets de la chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">D\u00e9calez les moments de p\u00e2turage la nuit, t\u00f4t le matin ou le soir.<\/li>\n\n\n\n<li>Pr\u00e9voyez toujours des zones ombrag\u00e9es dans les p\u00e2turages ou des abris bien ventil\u00e9s (en veillant \u00e0 \u00e9viter toute accumulation de chaleur en dessous).<\/li>\n\n\n\n<li>Assurez un acc\u00e8s permanent \u00e0 une grande quantit\u00e9 d\u2019eau (les chevaux ont besoin de jusqu\u2019\u00e0 70 litres d\u2019eau par jour en cas de forte chaleur).<\/li>\n\n\n\n<li>Une pierre \u00e0 l\u00e9cher au sel doit toujours \u00eatre \u00e0 leur disposition.<\/li>\n\n\n\n<li class=\"is-style-default\">Selon le cheval : limitez les entra\u00eenements et les sorties aux heures les plus fra\u00eeches de la journ\u00e9e (t\u00f4t le matin ou le soir).<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Equiden-1024x683.jpg\" alt=\"Prot\u00e9ger les chevaux, les \u00e2nes et les mulets de la chaleur\" class=\"wp-image-37343 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Equiden-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-un-cheval-un-ane-ou-un-mulet-est-en-surchauffe\"><strong><strong>Comment savoir si un cheval, un \u00e2ne ou un mulet est en surchauffe ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les sympt\u00f4mes courants de surchauffe et de coup de chaleur chez les chevaux, les \u00e2nes et les mulets sont la faiblesse, l\u2019apathie, des sympt\u00f4mes de type colique, une \u00e9l\u00e9vation de la temp\u00e9rature corporelle (sup\u00e9rieure \u00e0 38,5&nbsp;\u00b0C), une augmentation de la fr\u00e9quence cardiaque et une respiration rapide et superficielle pouvant aller jusqu\u2019\u00e0 l\u2019\u00e9tat de choc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Mettez imm\u00e9diatement l\u2019animal dans un endroit frais, proposez-lui de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"nutztiere\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-proteger-les-animaux-de-rente-et-de-paturage-de-la-chaleur\"><strong><strong>Prot\u00e9ger les animaux de rente et de p\u00e2turage de la chaleur<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Outre une \u00e9table fra\u00eeche, les animaux de p\u00e2turage ont id\u00e9alement besoin de p\u00e2turages nocturnes en \u00e9t\u00e9 et de zones ombrag\u00e9es aussi naturelles que possible pendant la journ\u00e9e. Il est \u00e9galement important qu\u2019ils aient un acc\u00e8s illimit\u00e9 \u00e0 l\u2019eau fra\u00eeche dans l\u2019\u00e9table et dans les p\u00e2turages.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-que-faire-si-vous-voyez-des-animaux-dans-les-paturages-sans-ombre-et-ou-sans-eau-par-temps-chaud\"><strong><strong>Que faire si vous voyez des animaux dans les p\u00e2turages sans ombre et\/ou sans eau par temps chaud ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Dans un premier temps, essayez d\u2019abord de contacter les d\u00e9tenteurs et d\u00e9tentrices de ces animaux. S\u2019ils ne sont pas joignables, informez la police ou l\u2019office v\u00e9t\u00e9rinaire. Conseil&nbsp;: souvent, les associations r\u00e9gionales de protection des animaux ou les v\u00e9t\u00e9rinaires peuvent \u00e9galement vous aider ou vous orienter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Attention&nbsp;:<\/strong> ne vous rendez jamais seul au milieu d\u2019un troupeau de vaches, surtout pas d\u2019un troupeau de vaches allaitantes&nbsp;! Ni au milieu d\u2019un troupeau de moutons&nbsp;: les chiens de protection des troupeaux, les b\u00e9liers, mais aussi les brebis pourraient se montrer agressifs. Si les animaux sont visiblement en d\u00e9tresse, vous pouvez essayer de leur apporter de l\u2019eau potable depuis l\u2019ext\u00e9rieur de l\u2019enclos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-vaches-et-les-boeufs\"><strong><strong>Rafra\u00eechir les vaches et les b\u0153ufs<\/strong><\/strong><\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les vaches et les b\u0153ufs aiment la fra\u00eecheur (entre 4 et 15\u00a0C\u00b0) et peuvent d\u00e9j\u00e0 souffrir de stress thermique lorsque les temp\u00e9ratures ext\u00e9rieures d\u00e9passent 24\u00a0\u00b0C et que l\u2019humidit\u00e9 de l\u2019air augmente. Ils peuvent \u00e9vacuer la chaleur par la respiration, mais cela entra\u00eene une augmentation de leur fr\u00e9quence respiratoire lorsque les temp\u00e9ratures sont \u00e9lev\u00e9es, ce qui est \u00e9prouvant pour ces animaux. Leur temp\u00e9rature corporelle augmente \u00e9galement, ce qui entra\u00eene un besoin accru de liquide \u2013 en cas de chaleur, les vaches ont besoin de 180\u00a0litres ou plus par jour.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flex wp-container-core-group-is-layout-0eba7147 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-style-shadow-box has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-au-paturage\"><strong>Au p\u00e2turage :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Garantissez un acc\u00e8s illimit\u00e9 \u00e0 de l\u2019eau fra\u00eeche.<\/li>\n\n\n\n<li>Il doit y avoir suffisamment de zones ombrag\u00e9es naturelles \u00e0 l\u2019int\u00e9rieur de la cl\u00f4ture (arbres, arbustes), en particulier pendant les heures les plus chaudes.<\/li>\n\n\n\n<li>S\u2019il n\u2019y a pas de source d\u2019ombre naturelle dans les p\u00e2turages, installez des abris adapt\u00e9s pour tous les animaux.<\/li>\n\n\n\n<li>Installez des syst\u00e8mes d\u2019ombrage dans des endroits secs avec de l\u00e9gers courants d\u2019air afin de pr\u00e9venir toute g\u00eane caus\u00e9e par les mouches.<\/li>\n\n\n\n<li class=\"is-style-default\">Lors de p\u00e9riodes durablement chaudes, il est recommand\u00e9 de laisser les animaux pa\u00eetre la nuit.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-style-shadow-box has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-dans-l-etable\"><strong>Dans l\u2019\u00e9table :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Garantissez un acc\u00e8s illimit\u00e9 \u00e0 de l\u2019eau fra\u00eeche.<\/li>\n\n\n\n<li>Pour que les vaches et les b\u0153ufs puissent se rafra\u00eechir, l\u2019\u00e9table doit disposer d\u2019un apport d\u2019air frais important.<\/li>\n\n\n\n<li>Pr\u00e9voyez suffisamment d\u2019espaces avec de l\u00e9gers courants d\u2019air \u2013 les vaches et les b\u0153ufs se tiennent souvent \u00e0 de tels endroits dans l\u2019\u00e9table.<\/li>\n\n\n\n<li>Une climatisation, des ventilateurs de plafond ou muraux et de plus grands ventilateurs sur pied facilitent l\u2019arriv\u00e9e d\u2019air.<\/li>\n\n\n\n<li>Les \u00e9tables modernes disposent de syst\u00e8mes d\u2019aspersion qui diffusent l\u2019eau sous forme de fine brume.<\/li>\n\n\n\n<li class=\"is-style-default\">Pour limiter la chaleur, privil\u00e9giez des \u00e9tables situ\u00e9es \u00e0 proximit\u00e9 d\u2019arbres ou avec des toits v\u00e9g\u00e9talis\u00e9s.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-une-vache-ou-un-boeuf-est-en-surchauffe\"><strong><strong>Comment savoir si une vache ou un b\u0153uf est en surchauffe ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Une vache et un b\u0153uf sont en surchauffe lorsqu\u2019ils transpirent, respirent difficilement et hal\u00e8tent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils doivent alors \u00eatre soulag\u00e9s le plus rapidement possible par des mesures de refroidissement appropri\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Permettez-leur de se retirer imm\u00e9diatement au frais dans l\u2019\u00e9table avec un approvisionnement suffisant en eau, aidez-les \u00e0 se rafra\u00eechir en les aspergeant plusieurs fois d\u2019eau froide (avec de courtes pauses entre les arrosages pour l\u2019\u00e9vaporation) et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-porcs\"><strong><strong>Rafra\u00eechir les porcs<\/strong><\/strong><\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les porcs transpirent tr\u00e8s peu. Ils n\u2019ont de glandes sudoripares qu\u2019au niveau du groin et entre les orteils. Celles-ci ne suffisent pas pour se rafra\u00eechir \u00e0 l\u2019ext\u00e9rieur, dans les p\u00e2turages, lorsque la temp\u00e9rature d\u00e9passe les 25 \u00b0C. Ils ont donc besoin de suffisamment de possibilit\u00e9s de rafra\u00eechissement et d\u2019une bonne protection contre le soleil.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Schwein-1024x767.jpg\" alt=\"Prot\u00e9ger les porcs de la chaleur\" class=\"wp-image-37355 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-1024x767.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-300x225.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-768x575.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-1536x1151.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-2048x1534.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-500x375.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-800x599.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-1280x959.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schwein-1920x1438.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-porcs-de-la-chaleur\"><strong>Prot\u00e9ger les porcs de la chaleur<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Pr\u00e9voyez suffisamment de zones ombrag\u00e9es et un acc\u00e8s \u00e0 de l\u2019eau fra\u00eeche en abondance.<\/li>\n\n\n\n<li>Les \u00e9tables climatis\u00e9es sont \u00e0 privil\u00e9gier, car les porcs sont sensibles \u00e0 la chaleur.<\/li>\n\n\n\n<li>Mais si les p\u00e2turages sont am\u00e9nag\u00e9s de mani\u00e8re \u00e0 offrir suffisamment de zones ombrag\u00e9es et d\u2019eau potable, les porcs peuvent \u00eatre \u00e9lev\u00e9s en plein air, m\u00eame en \u00e9t\u00e9.<\/li>\n\n\n\n<li class=\"is-style-default\">Les porcs de p\u00e2turage ont besoin d\u2019un sol frais pour s\u2019allonger et d\u2019une mare de boue profonde dans laquelle ils peuvent se vautrer tout en se refroidissant (la boue les prot\u00e8ge en outre des coups de soleil).<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-un-porc-est-en-surchauffe\"><strong><strong>Comment savoir si un porc est en surchauffe ?<\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les signes suivants indiquent un stress thermique chez les porcs&nbsp;: respiration acc\u00e9l\u00e9r\u00e9e, allongement fr\u00e9quent dans des endroits froids\/humides et temp\u00e9rature corporelle \u00e9lev\u00e9e. Une queue pendante ou raidie peut aussi \u00eatre un signe de surchauffe. Ils doivent alors \u00eatre soulag\u00e9s le plus rapidement possible par des mesures de refroidissement appropri\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Permettez-leur de se retirer imm\u00e9diatement dans l\u2019\u00e9table fra\u00eeche avec un acc\u00e8s \u00e0 de l\u2019eau fra\u00eeche en abondance et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-poules\"><strong><strong>Rafra\u00eechir les poules<\/strong><\/strong><\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Les poules sont rapidement sujettes au stress thermique : \u00e0 partir de 28 \u00b0C et d\u2019une humidit\u00e9 de l\u2019air croissante, elles ont du mal \u00e0 r\u00e9guler leur temp\u00e9rature corporelle. Elles ne peuvent pas transpirer et essaient d\u2019\u00e9vacuer la chaleur par la langue, les muqueuses, les ailes et la peau. Toutefois, lorsque les temp\u00e9ratures sont \u00e9lev\u00e9es et que l\u2019air circule mal, cela ne suffit pas \u00e0 les refroidir.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-poules-de-la-chaleur\"><strong>Prot\u00e9ger les poules de la chaleur<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Proposez de l\u2019eau fra\u00eeche \u00e0 plusieurs endroits du poulailler afin d\u2019\u00e9viter les attroupements autour de l\u2019abreuvoir.<\/li>\n\n\n\n<li>Veillez \u00e0 ce qu\u2019il y ait beaucoup d\u2019air frais et une bonne circulation de l\u2019air dans le poulailler.<\/li>\n\n\n\n<li>Les poules \u00e9lev\u00e9es en plein air ont besoin de suffisamment de zones ombrag\u00e9es, aussi naturelles que possible.<\/li>\n\n\n\n<li class=\"is-style-default\">Les bains de sable \u00e0 l\u2019ombre (zones de sol sec) offrent aux poules un moyen de se rafra\u00eechir.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Huehner-1024x683.jpg\" alt=\"Prot\u00e9ger les poules de la chaleur\" class=\"wp-image-37346 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Huehner-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-une-poule-est-en-surchauffe\"><strong><strong><strong>Comment savoir si une poule est en surchauffe ?<\/strong><\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les signes d\u2019une surchauffe chez les poules sont les suivants&nbsp;: bec ouvert et hal\u00e8tements (silencieux), ailes \u00e9cart\u00e9es ou pendantes, faiblesse, apathie, perte d\u2019app\u00e9tit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Mettez imm\u00e9diatement les animaux dans un endroit frais, proposez-leur de l\u2019eau fra\u00eeche et appelez directement le v\u00e9t\u00e9rinaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-rafraichir-les-moutons\"><strong><strong><strong>Rafra\u00eechir les moutons<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Pour la p\u00e9riode estivale de p\u00e2turage, les moutons doivent \u00eatre tondus au plus tard en juin. Leur toison devient de plus en plus dense et, en raison de la charge \u00e9lev\u00e9e de la laine, provoque un stress thermique et une accumulation de chaleur d\u00e8s 25 \u00b0C les jours d\u2019\u00e9t\u00e9, ce qui peut entra\u00eener une mort douloureuse pour ces animaux. Mais la tonte ne suffit pas \u00e0 prot\u00e9ger les moutons de la chaleur.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Schafe-1024x683.jpg\" alt=\"Prot\u00e9ger les moutons de la chaleur\" class=\"wp-image-37353 size-full\" style=\"object-position:49% 59%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-1024x683.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-300x200.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-768x512.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-1536x1024.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-2048x1365.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-500x333.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-800x533.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-1280x853.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Schafe-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-proteger-les-moutons-de-la-chaleur\"><strong>Prot\u00e9ger les moutons de la chaleur<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Veillez \u00e0 garantir un acc\u00e8s illimit\u00e9 \u00e0 l\u2019eau fra\u00eeche ainsi qu\u2019\u00e0 diff\u00e9rents points d\u2019abreuvement (les moutons ont besoin d\u2019environ 2 \u00e0 4 litres d\u2019eau par jour. Les brebis allaitantes et la chaleur estivale peuvent porter ce besoin \u00e0 plus de 10 litres par jour et par animal !)<\/li>\n\n\n\n<li>Pr\u00e9voyez de nombreuses zones ombrag\u00e9es pouvant accueillir tous les animaux, d\u2019autant plus que leur toison raccourcie ne prot\u00e8ge pas suffisamment la peau des coups de soleil.<\/li>\n\n\n\n<li class=\"is-style-default\">En l\u2019absence de sources d\u2019ombre naturelles, veillez \u00e0 cr\u00e9er des sources d\u2019ombre artificielles.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-style-accordion is-layout-flex wp-container-core-columns-is-layout-0173da89 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-savoir-si-un-mouton-est-en-surchauffe\"><strong><strong><strong>Comment savoir si un mouton est en surchauffe ?<\/strong><\/strong><\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les signes suivants peuvent indiquer une surchauffe chez les moutons&nbsp;: respiration acc\u00e9l\u00e9r\u00e9e et superficielle, narines dilat\u00e9es, t\u00eates et oreilles pendantes et animaux qui s\u2019isolent du troupeau et restent souvent couch\u00e9s. Ils doivent alors \u00eatre soulag\u00e9s le plus rapidement possible par des mesures de refroidissement appropri\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2192 Permettez-leur de se retirer imm\u00e9diatement dans un endroit plus frais, proposez de l\u2019eau et appelez directement le v\u00e9t\u00e9rinaire. Le cas \u00e9ch\u00e9ant, il est possible d\u2019humidifier certaines zones cutan\u00e9es, mais il ne faut pas arroser enti\u00e8rement les animaux avec de l\u2019eau.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" id=\"wildtiere\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-animaux-sauvages-et-chaleur\"><strong><strong>Animaux sauvages et chaleur<\/strong><\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-color has-alpha-channel-opacity has-primary-background-color has-background\"\/>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Lorsque des points d\u2019eau naturels tels que les ruisseaux, les \u00e9tangs ou les flaques s\u2019ass\u00e8chent, l\u2019eau se rar\u00e9fie pour les animaux sauvages, en particulier dans les villes et les zones industrielles. Des moyens simples permettent d\u2019am\u00e9nager des points d\u2019eau suppl\u00e9mentaires dans le jardin ou sur le balcon.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-shadow\" id=\"anker\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading\" id=\"h-comment-aider-les-animaux-sauvages-en-cas-de-chaleur\"><strong>Comment aider les animaux sauvages en cas de chaleur :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"is-style-default\">Placez des r\u00e9cipients d\u2019eau peu profonds (les soucoupes des pots de fleurs sont id\u00e9ales) dans le jardin ou sur le balcon. <br><strong>Attention\u00a0:<\/strong> les pots ou seaux profonds ne sont pas adapt\u00e9s, car il existe un risque de noyade pour les petits animaux.<\/li>\n\n\n\n<li>Placez de petits cailloux ou des morceaux de bois dans le r\u00e9cipient d\u2019eau pour que les insectes puissent s\u2019extraire facilement.<\/li>\n\n\n\n<li>Changez l\u2019eau tous les jours et nettoyez le r\u00e9cipient (eau chaude et brosse \u2013 pas de produits chimiques\u00a0!) afin d\u2019\u00e9viter la transmission d\u2019agents pathog\u00e8nes.<\/li>\n\n\n\n<li>Si possible, placez les coupelles \u00e0 l\u2019ombre et pas directement \u00e0 proximit\u00e9 directe d\u2019un buisson ou autre, car des chats peuvent s\u2019y cacher.<\/li>\n\n\n\n<li>Une v\u00e9g\u00e9tation dense, des haies et des fleurs sauvages offrent de l\u2019ombre, maintiennent l\u2019humidit\u00e9 dans le sol et offrent protection et nourriture.<\/li>\n\n\n\n<li>Les plantes en pot sur le balcon avec des fleurs sauvages offrent nourriture et protection aux insectes.<\/li>\n\n\n\n<li class=\"is-style-default\">L\u2019empilement de branches et de feuilles mortes dans le jardin cr\u00e9e des refuges et des zones ombrag\u00e9es. Pour les oiseaux, privil\u00e9giez les abreuvoirs sur\u00e9lev\u00e9s ou suspendus ainsi que les bains d\u2019oiseaux.<\/li>\n<\/ul>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"599\" src=\"https:\/\/tierschutz.com\/app\/uploads\/2026\/05\/Igel-1024x599.jpg\" alt=\"Comment aider les animaux sauvages en cas de chaleur\" class=\"wp-image-37348 size-full\" style=\"object-position:50% 50%\" srcset=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-1024x599.jpg 1024w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-300x175.jpg 300w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-768x449.jpg 768w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-1536x898.jpg 1536w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-2048x1198.jpg 2048w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-500x292.jpg 500w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-800x468.jpg 800w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-1280x748.jpg 1280w, https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Igel-1920x1123.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:1.5em\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention, il est important de bien conna\u00eetre leurs besoins et de prendre \u00e0 temps les mesures n\u00e9cessaires pour qu\u2019ils puissent se rafra\u00eechir. C\u2019est le seul moyen d\u2019\u00e9viter efficacement la surchauffe et les risques pour la sant\u00e9.<\/p>\n","protected":false},"author":5,"featured_media":37390,"parent":4302,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-37391","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les animaux et la chaleur estivale - Protection Suisse des Animaux PSA<\/title>\n<meta name=\"description\" content=\"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les animaux et la chaleur estivale\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/\" \/>\n<meta property=\"og:site_name\" content=\"Protection Suisse des Animaux PSA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/schweizertierschutz\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T11:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sts-psa.ch\/app\/uploads\/2026\/05\/Headerbild-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/\",\"url\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/\",\"name\":\"Les animaux et la chaleur estivale - Protection Suisse des Animaux PSA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/app\\\/uploads\\\/2026\\\/05\\\/Headerbild.jpg\",\"datePublished\":\"2026-05-28T14:35:01+00:00\",\"dateModified\":\"2026-05-29T11:47:22+00:00\",\"description\":\"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/app\\\/uploads\\\/2026\\\/05\\\/Headerbild.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/app\\\/uploads\\\/2026\\\/05\\\/Headerbild.jpg\",\"width\":2501,\"height\":1667,\"caption\":\"black labrador looking through car window\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/les-animaux-et-la-chaleur-estivale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d\u2019accueil\",\"item\":\"https:\\\/\\\/mail.protezione-animali-psa.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection des animaux\u00a0\",\"item\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rubriques\",\"item\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/fr\\\/protection-des-animaux\\\/rubriques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les animaux et la chaleur estivale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#website\",\"url\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/\",\"name\":\"tierschutz.com\",\"description\":\"Wir setzen uns f\u00fcr das Wohl der Tiere ein.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#organization\"},\"alternateName\":\"Schweizer Tierschutz STS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#organization\",\"name\":\"Schweizer Tierschutz STS\",\"alternateName\":\"STS\",\"url\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"contentUrl\":\"https:\\\/\\\/mail.schweizer-tierschutz-sts.ch\\\/app\\\/uploads\\\/2024\\\/04\\\/logo-schweizer-tierschutz-sts-1.svg\",\"caption\":\"Schweizer Tierschutz STS\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.protection-animaux-psa.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/schweizertierschutz\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schweizertierschutzsts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@STS_Tierschutz\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/schweizertierschutzsts\\\/\"],\"description\":\"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.\",\"email\":\"sts@tierschutz.com\",\"telephone\":\"061 365 99 99\",\"legalName\":\"Schweizer Tierschutz STS\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les animaux et la chaleur estivale - Protection Suisse des Animaux PSA","description":"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/","og_locale":"fr_FR","og_type":"article","og_title":"Les animaux et la chaleur estivale","og_description":"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.","og_url":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/","og_site_name":"Protection Suisse des Animaux PSA","article_publisher":"https:\/\/www.facebook.com\/schweizertierschutz\/","article_modified_time":"2026-05-29T11:47:22+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/sts-psa.ch\/app\/uploads\/2026\/05\/Headerbild-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/","url":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/","name":"Les animaux et la chaleur estivale - Protection Suisse des Animaux PSA","isPartOf":{"@id":"https:\/\/mail.protection-animaux-psa.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/#primaryimage"},"image":{"@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild.jpg","datePublished":"2026-05-28T14:35:01+00:00","dateModified":"2026-05-29T11:47:22+00:00","description":"Les \u00e9t\u00e9s sont de plus en plus chauds. Cela affecte non seulement les \u00eatres humains, mais aussi les animaux. \u00c9tant donn\u00e9 que les animaux domestiques d\u00e9pendent de leurs conditions de d\u00e9tention.","breadcrumb":{"@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/#primaryimage","url":"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild.jpg","contentUrl":"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2026\/05\/Headerbild.jpg","width":2501,"height":1667,"caption":"black labrador looking through car window"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/les-animaux-et-la-chaleur-estivale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d\u2019accueil","item":"https:\/\/mail.protezione-animali-psa.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection des animaux\u00a0","item":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/"},{"@type":"ListItem","position":3,"name":"Rubriques","item":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/protection-des-animaux\/rubriques\/"},{"@type":"ListItem","position":4,"name":"Les animaux et la chaleur estivale"}]},{"@type":"WebSite","@id":"https:\/\/mail.protection-animaux-psa.ch\/#website","url":"https:\/\/mail.protection-animaux-psa.ch\/","name":"tierschutz.com","description":"Wir setzen uns f\u00fcr das Wohl der Tiere ein.","publisher":{"@id":"https:\/\/mail.protection-animaux-psa.ch\/#organization"},"alternateName":"Schweizer Tierschutz STS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.protection-animaux-psa.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.protection-animaux-psa.ch\/#organization","name":"Schweizer Tierschutz STS","alternateName":"STS","url":"https:\/\/mail.protection-animaux-psa.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.protection-animaux-psa.ch\/#\/schema\/logo\/image\/","url":"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","contentUrl":"https:\/\/mail.schweizer-tierschutz-sts.ch\/app\/uploads\/2024\/04\/logo-schweizer-tierschutz-sts-1.svg","caption":"Schweizer Tierschutz STS"},"image":{"@id":"https:\/\/mail.protection-animaux-psa.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/schweizertierschutz\/","https:\/\/www.instagram.com\/schweizertierschutzsts\/","https:\/\/www.youtube.com\/@STS_Tierschutz","https:\/\/www.linkedin.com\/company\/schweizertierschutzsts\/"],"description":"Der Schweizer Tierschutz STS ist der Dachverband von 71 Tierschutzorganisationen in allen Sprachregionen der Schweiz und in Liechtenstein. Seine Mitarbeitenden leisten wissenschaftlich fundierte Grundlagenarbeit, setzen sich mit Projekten und Aktionen f\u00fcr den Schutz und das Wohlbefinden von Heim-, Wild-, Nutz- und Versuchstieren ein und sensibilisieren die \u00d6ffentlichkeit f\u00fcr Tierschutzthemen.","email":"sts@tierschutz.com","telephone":"061 365 99 99","legalName":"Schweizer Tierschutz STS"}]}},"_links":{"self":[{"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/pages\/37391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/comments?post=37391"}],"version-history":[{"count":7,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/pages\/37391\/revisions"}],"predecessor-version":[{"id":37408,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/pages\/37391\/revisions\/37408"}],"up":[{"embeddable":true,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/pages\/4302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/media\/37390"}],"wp:attachment":[{"href":"https:\/\/mail.schweizer-tierschutz-sts.ch\/fr\/wp-json\/wp\/v2\/media?parent=37391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}